{"id":12299,"date":"2020-02-03T10:44:01","date_gmt":"2020-02-03T09:44:01","guid":{"rendered":"https:\/\/monnaber.com\/wp-content\/uploads\/2020\/02\/flor-almendro-mallorca-2.jpg"},"modified":"2020-02-03T10:44:01","modified_gmt":"2020-02-03T09:44:01","slug":"flor-almendro-mallorca-2","status":"inherit","type":"attachment","link":"https:\/\/monnaber.com\/es\/oferta-verano-hotel-monnaber-nou-mallorca\/flor-almendro-mallorca-2\/","title":{"rendered":"flor almendro mallorca 2"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-12299","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/monnaber.com\/wp-content\/uploads\/2020\/02\/flor-almendro-mallorca-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/monnaber.com\/wp-content\/uploads\/2020\/02\/flor-almendro-mallorca-2-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"- -\" srcset=\"https:\/\/monnaber.com\/wp-content\/uploads\/2020\/02\/flor-almendro-mallorca-2-300x200.jpg 300w, https:\/\/monnaber.com\/wp-content\/uploads\/2020\/02\/flor-almendro-mallorca-2-219x146.jpg 219w, https:\/\/monnaber.com\/wp-content\/uploads\/2020\/02\/flor-almendro-mallorca-2-50x33.jpg 50w, https:\/\/monnaber.com\/wp-content\/uploads\/2020\/02\/flor-almendro-mallorca-2-113x75.jpg 113w, https:\/\/monnaber.com\/wp-content\/uploads\/2020\/02\/flor-almendro-mallorca-2-528x352.jpg 528w, https:\/\/monnaber.com\/wp-content\/uploads\/2020\/02\/flor-almendro-mallorca-2.jpg 690w\" sizes=\"auto, (max-width:767px) 300px, 300px\" title=\"- -\"><\/a><\/p>\n- -"},"caption":{"rendered":"<p>&#8211; &#8211;<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":690,"height":460,"file":"2020\/02\/flor-almendro-mallorca-2.jpg","sizes":{"thumbnail":{"file":"flor-almendro-mallorca-2-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/monnaber.com\/wp-content\/uploads\/2020\/02\/flor-almendro-mallorca-2-150x150.jpg"},"medium":{"file":"flor-almendro-mallorca-2-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/monnaber.com\/wp-content\/uploads\/2020\/02\/flor-almendro-mallorca-2-300x200.jpg"},"post-thumbnail":{"file":"flor-almendro-mallorca-2-219x146.jpg","width":219,"height":146,"mime_type":"image\/jpeg","source_url":"https:\/\/monnaber.com\/wp-content\/uploads\/2020\/02\/flor-almendro-mallorca-2-219x146.jpg"},"50x50":{"file":"flor-almendro-mallorca-2-50x33.jpg","width":50,"height":33,"mime_type":"image\/jpeg","source_url":"https:\/\/monnaber.com\/wp-content\/uploads\/2020\/02\/flor-almendro-mallorca-2-50x33.jpg"},"clients-slider":{"file":"flor-almendro-mallorca-2-113x75.jpg","width":113,"height":75,"mime_type":"image\/jpeg","source_url":"https:\/\/monnaber.com\/wp-content\/uploads\/2020\/02\/flor-almendro-mallorca-2-113x75.jpg"},"testimonials":{"file":"flor-almendro-mallorca-2-85x85.jpg","width":85,"height":85,"mime_type":"image\/jpeg","source_url":"https:\/\/monnaber.com\/wp-content\/uploads\/2020\/02\/flor-almendro-mallorca-2-85x85.jpg"},"blog-navi":{"file":"flor-almendro-mallorca-2-80x80.jpg","width":80,"height":80,"mime_type":"image\/jpeg","source_url":"https:\/\/monnaber.com\/wp-content\/uploads\/2020\/02\/flor-almendro-mallorca-2-80x80.jpg"},"_mailster-528x352|":{"file":"flor-almendro-mallorca-2-528x352.jpg","width":528,"height":352,"mime_type":"image\/jpeg","source_url":"https:\/\/monnaber.com\/wp-content\/uploads\/2020\/02\/flor-almendro-mallorca-2-528x352.jpg"},"full":{"file":"flor-almendro-mallorca-2.jpg","width":690,"height":460,"mime_type":"image\/jpeg","source_url":"https:\/\/monnaber.com\/wp-content\/uploads\/2020\/02\/flor-almendro-mallorca-2.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":12302,"source_url":"https:\/\/monnaber.com\/wp-content\/uploads\/2020\/02\/flor-almendro-mallorca-2.jpg","filename":"flor-almendro-mallorca-2.jpg","filesize":170879,"_links":{"self":[{"href":"https:\/\/monnaber.com\/es\/wp-json\/wp\/v2\/media\/12299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monnaber.com\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/monnaber.com\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/monnaber.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/monnaber.com\/es\/wp-json\/wp\/v2\/comments?post=12299"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":12302,"href":"https:\/\/monnaber.com\/es\/wp-json\/wp\/v2\/pages\/12302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}