{"id":6839,"date":"2019-03-05T12:28:59","date_gmt":"2019-03-05T11:28:59","guid":{"rendered":"https:\/\/monnaber.com\/?p=6839"},"modified":"2019-03-05T12:28:59","modified_gmt":"2019-03-05T11:28:59","slug":"fruehling","status":"publish","type":"post","link":"https:\/\/monnaber.com\/de\/fruehling\/","title":{"rendered":"Fr\u00fchling"},"content":{"rendered":"<h4>Am 20. M\u00e4rz beginnt der Fr\u00fchling. Der Fr\u00fchlingsanfang verwandelt die Essenz der mallorquinischen Landschaft, ver\u00e4ndert die Stimmung der Menschen, die Tage sind l\u00e4nger, mehr Farben, Ger\u00fcche, Kurz gesagt, mehr Leben.<\/h4>\n<h4><\/h4>\n<h4>Fr\u00fchling ist die Umformzeit. Die Natur ver\u00e4ndert die grauen und dunklen T\u00f6ne, durch die Farben der Bl\u00fcten, durch das intensive Sonnenlicht, durch die Temperaturerh\u00f6hung.<\/h4>\n<h4><\/h4>\n<h4>Das Hotel Rural &amp; Spa Monn\u00e1ber Nou ist ein Hotel im Norden der Insel Mallorca, in dem Sie die einheimische Natur der Insel intensiv genie\u00dfen k\u00f6nnen. Die Vegetation, die Tiere, kurz die Umgebung des Hotels, l\u00e4sst den Kunden ein unvergessliches Erlebnis erleben.<\/h4>\n<h4><\/h4>\n<h4>An der Hotelrezeption k\u00f6nnen wir Sie \u00fcber alles informieren, was Sie \u00fcber unser Hotel, unsere Angebote und alles, was Sie brauchen, wissen m\u00fcssen.<\/h4>\n<h4>Auf der Website monnaber.com oder telefonisch unter 971 87 71 76 k\u00f6nnen Sie uns kontaktieren und wir werden Ihnen helfen.<\/h4>\n<h4><\/h4>\n","protected":false},"excerpt":{"rendered":"<p>Am 20. M\u00e4rz beginnt der Fr\u00fchling. Der Fr\u00fchlingsanfang verwandelt die Essenz der mallorquinischen Landschaft, ver\u00e4ndert die Stimmung der Menschen, die Tage sind l\u00e4nger, mehr Farben, Ger\u00fcche,<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":10,"featured_media":5956,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[243,271,4],"tags":[],"class_list":["post-6839","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-events-de","category-mallorca-de","category-unkategorisiert"],"_links":{"self":[{"href":"https:\/\/monnaber.com\/de\/wp-json\/wp\/v2\/posts\/6839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monnaber.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monnaber.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monnaber.com\/de\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/monnaber.com\/de\/wp-json\/wp\/v2\/comments?post=6839"}],"version-history":[{"count":0,"href":"https:\/\/monnaber.com\/de\/wp-json\/wp\/v2\/posts\/6839\/revisions"}],"wp:attachment":[{"href":"https:\/\/monnaber.com\/de\/wp-json\/wp\/v2\/media?parent=6839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monnaber.com\/de\/wp-json\/wp\/v2\/categories?post=6839"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monnaber.com\/de\/wp-json\/wp\/v2\/tags?post=6839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}